{"id":306,"date":"2020-12-16T12:19:31","date_gmt":"2020-12-16T11:19:31","guid":{"rendered":"http:\/\/snudifo34.fr\/?p=306"},"modified":"2020-12-16T12:21:05","modified_gmt":"2020-12-16T11:21:05","slug":"m-castex-lecole-nest-pas-une-garderie","status":"publish","type":"post","link":"http:\/\/snudifo34.fr\/index.php\/2020\/12\/16\/m-castex-lecole-nest-pas-une-garderie\/","title":{"rendered":"M. Castex, l&rsquo;\u00e9cole n&rsquo;est pas une garderie !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La FNEC FP-FO d\u00e9fend l\u2019\u00e9cole la\u00efque, publique et obligatoire<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encore une fois, le gouvernement et son conseil scientifique ont d\u00e9cid\u00e9 de changer les r\u00e8gles au dernier moment sans demander l\u2019avis de personne.<br>Les personnels ont ainsi appris, ce matin, par voie de presse, qu\u2019ils devraient faire preuve de \u00ab tol\u00e9rance \u00bb pour permettre aux \u00e9l\u00e8ves de se confiner afin de participer aux f\u00eates de No\u00ebl en compagnie de leur famille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>On croit r\u00eaver ou assister \u00e0 une mauvaise farce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Ceux qui aujourd\u2019hui recommandent de garder les enfants \u00e0 la maison sont les m\u00eames que ceux qui pr\u00e9tendaient que ces derniers n\u2019\u00e9taient pas contagieux.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Ceux qui usent et abusent de la formule \u00ab continuit\u00e9 p\u00e9dagogique \u00bb sont les m\u00eames qui font fi de la progression p\u00e9dagogique des professeurs et qui foulent aux pieds leur travail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Les personnels n\u2019en peuvent plus de ces ordres et contre-ordres permanents.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>C\u2019est une nouvelle illustration de la conception de l\u2019\u00e9cole que cherche \u00e0 imposer la pr\u00e9sidence Macron \u00e0 la faveur de la crise, une \u00e9cole \u00e0 la carte o\u00f9 la d\u00e9cision politique peut supplanter les cadres et les r\u00e8gles nationales, du jour au lendemain. C\u2019est le fait du prince.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pour la FNEC FP-FO, l\u2019\u00e9tat ne peut se soustraire \u00e0 ses devoirs, d\u00e9finis dans le pr\u00e9ambule de la Constitution de 1946, qui est de garantir \u00ab l\u2019\u00e9gal acc\u00e8s de l\u2019enfant (&#8230;) \u00e0 l\u2019instruction. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Il est \u00e9tonnant qu\u2019un Premier ministre propose aux familles de choisir entre le droit \u00e0 la sant\u00e9 et le droit \u00e0 l\u2019instruction sans envisager de prendre des mesures pour garantir l\u2019un et l\u2019autre.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>L\u2019\u00e9cole n\u2019est pas une garderie. Les personnels en ont assez de ce m\u00e9pris !<br>La FNEC FP-FO invite les personnels \u00e0 programmer d\u00e8s maintenant les heures d\u2019information syndicale et les AG, pour, d\u00e8s la rentr\u00e9e, pr\u00e9parer la gr\u00e8ve du 26 janvier, \u00e0 l\u2019appel FO, FSU,<br>CGT, SUD et SNCL.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/snudifo34.fr\/wp-content\/uploads\/2020\/12\/20-12-15-lecole-nest-pas-une-garderie.pdf\">T\u00e9l\u00e9charger le communiqu\u00e9 du 15\/12\/20<\/a><a href=\"http:\/\/snudifo34.fr\/wp-content\/uploads\/2020\/12\/20-12-15-lecole-nest-pas-une-garderie.pdf\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La FNEC FP-FO d\u00e9fend l\u2019\u00e9cole la\u00efque, publique et obligatoire Encore une fois, le gouvernement et son conseil scientifique ont d\u00e9cid\u00e9 de changer les r\u00e8gles au <a class=\"mh-excerpt-more\" href=\"http:\/\/snudifo34.fr\/index.php\/2020\/12\/16\/m-castex-lecole-nest-pas-une-garderie\/\" title=\"M. Castex, l&rsquo;\u00e9cole n&rsquo;est pas une garderie !\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":310,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[15],"tags":[92,95,94,93,96],"class_list":["post-306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques","tag-castex","tag-droit-a-instruction","tag-droit-a-la-sante","tag-ecole-a-la-carte","tag-noel"],"_links":{"self":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":1,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"predecessor-version":[{"id":309,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/306\/revisions\/309"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/media\/310"}],"wp:attachment":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}