{"id":7630,"date":"2026-01-23T18:12:03","date_gmt":"2026-01-23T17:12:03","guid":{"rendered":"https:\/\/snudifo34.fr\/?p=7630"},"modified":"2026-01-23T18:12:03","modified_gmt":"2026-01-23T17:12:03","slug":"concessions-avancees-sociales-non-lecornu-impose-par-49-3-son-budget-dausterite-et-de-guerre","status":"publish","type":"post","link":"http:\/\/snudifo34.fr\/index.php\/2026\/01\/23\/concessions-avancees-sociales-non-lecornu-impose-par-49-3-son-budget-dausterite-et-de-guerre\/","title":{"rendered":"\u00ab Concessions \u00bb ? \u00ab Avanc\u00e9es sociales \u00bb ? Non ! Lecornu impose par 49-3 son budget d\u2019aust\u00e9rit\u00e9 et de guerre"},"content":{"rendered":"\n<p>La FNEC FP-FO n\u2019est pas dupe des derni\u00e8res annonces du premier ministre Lecornu : son budget, c\u2019est toujours plus d\u2019argent pour l\u2019arm\u00e9e, des cadeaux fiscaux aux grandes entreprises et une offensive in\u00e9dite contre la S\u00e9cu, contre l\u2019Ecole publique, contre l\u2019h\u00f4pital public, contre les droitset le s garanties collectives des salari\u00e9s.<\/p>\n\n\n<a href=\"http:\/\/snudifo34.fr\/wp-content\/uploads\/2026\/01\/26-01-19-Communique-Budget-Lecornu-49-3.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">26-01-19-Communique-Budget-Lecornu-49-3<\/a>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La FNEC FP-FO n\u2019est pas dupe des derni\u00e8res annonces du premier ministre Lecornu : son budget, c\u2019est toujours plus d\u2019argent pour l\u2019arm\u00e9e, des cadeaux fiscaux <a class=\"mh-excerpt-more\" href=\"http:\/\/snudifo34.fr\/index.php\/2026\/01\/23\/concessions-avancees-sociales-non-lecornu-impose-par-49-3-son-budget-dausterite-et-de-guerre\/\" title=\"\u00ab Concessions \u00bb ? \u00ab Avanc\u00e9es sociales \u00bb ? Non ! Lecornu impose par 49-3 son budget d\u2019aust\u00e9rit\u00e9 et de guerre\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[28,15,303,306,305,292,302,113,471,310,112],"tags":[531,505,538,487],"class_list":["post-7630","post","type-post","status-publish","format-standard","hentry","category-aesh","category-communiques","category-contractuels","category-defense-de-lecole","category-directeurs","category-le-syndicat","category-pe","category-personnels","category-psyen","category-remplacants-trs-zil-brigade","category-stagiaires","tag-budget-2026","tag-coupes-budgetaires","tag-non-au-budget-de-guerre","tag-revendications"],"_links":{"self":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/7630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7630"}],"version-history":[{"count":1,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/7630\/revisions"}],"predecessor-version":[{"id":7633,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/7630\/revisions\/7633"}],"wp:attachment":[{"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7630"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}