{"id":7512,"date":"2025-12-30T19:17:40","date_gmt":"2025-12-30T18:17:40","guid":{"rendered":"https:\/\/snudifo34.fr\/?p=7512"},"modified":"2025-12-30T19:18:48","modified_gmt":"2025-12-30T18:18:48","slug":"motion-de-soutien-aux-enseignants-de-cisjordanie-en-greve","status":"publish","type":"post","link":"https:\/\/snudifo34.fr\/index.php\/2025\/12\/30\/motion-de-soutien-aux-enseignants-de-cisjordanie-en-greve\/","title":{"rendered":"Motion de soutien aux enseignants de Cisjordanie en gr\u00e8ve"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans le contexte de l\u2019occupation militaire de la Cisjordanie et de l\u2019intensification des violences coloniales, les enseignants gr\u00e9vistes ne font qu\u2019exiger la d\u00e9fense de l\u2019\u00e9cole et de la qualit\u00e9 de l\u2019enseignement, \u00e9l\u00e9ment majeur de la r\u00e9sistance des peuples \u00e0 l\u2019oppression.<\/p>\n\n\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/snudifo34.fr\/wp-content\/uploads\/2025\/12\/25-12-20-Motion-de-soutien-aux-enseignants-de-Cisjordanie-en-greve.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">25-12-20-Motion-de-soutien-aux-enseignants-de-Cisjordanie-en-greve<\/a><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Dans le contexte de l\u2019occupation militaire de la Cisjordanie et de l\u2019intensification des violences coloniales, les enseignants gr\u00e9vistes ne font qu\u2019exiger la d\u00e9fense de l\u2019\u00e9cole <a class=\"mh-excerpt-more\" href=\"https:\/\/snudifo34.fr\/index.php\/2025\/12\/30\/motion-de-soutien-aux-enseignants-de-cisjordanie-en-greve\/\" title=\"Motion de soutien aux enseignants de Cisjordanie en gr\u00e8ve\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[15,292,1],"tags":[59,532,487],"class_list":["post-7512","post","type-post","status-publish","format-standard","hentry","category-communiques","category-le-syndicat","category-non-classe","tag-greve","tag-palestine","tag-revendications"],"_links":{"self":[{"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/7512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7512"}],"version-history":[{"count":2,"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/7512\/revisions"}],"predecessor-version":[{"id":7515,"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/posts\/7512\/revisions\/7515"}],"wp:attachment":[{"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snudifo34.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}